{"id":24962,"date":"2024-03-26T14:55:54","date_gmt":"2024-03-26T20:55:54","guid":{"rendered":"https:\/\/www.sportium.com.mx\/blog\/?p=24962"},"modified":"2024-03-26T14:55:56","modified_gmt":"2024-03-26T20:55:56","slug":"mitos-falsos-del-deporte","status":"publish","type":"post","link":"https:\/\/www.sportium.com.mx\/blog\/mitos-falsos-del-deporte\/","title":{"rendered":"Mitos Falsos del Deporte"},"content":{"rendered":"<p>Los mitos falsos del deporte son creencias err\u00f3neas que han persistido a lo largo del tiempo y que pueden afectar la forma en que las personas se relacionan con la actividad f\u00edsica.<\/p>\n<p>Son muchas las falsas creencias que rodean el mundo del deporte y la salud, algunas de ellas muy arraigadas en la poblaci\u00f3n.<\/p>\n<p>Estos mitos pueden llevarnos a pr\u00e1cticas deportivas in\u00fatiles o incluso peligrosas para nuestra salud.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25029\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=706%2C331&#038;ssl=1\" alt=\"\" width=\"706\" height=\"331\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?w=706&amp;ssl=1 706w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=300%2C141&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=500%2C233&amp;ssl=1 500w\" sizes=\"(max-width: 706px) 100vw, 706px\" \/><\/a><\/p>\n<p>A continuaci\u00f3n te compartimos los mitos falsos m\u00e1s comunes y populares que existen y que hasta la fecha contin\u00faan siendo un tema de conversaci\u00f3n y duda entre las personas.<\/p>\n<h4>1. Sudar adelgaza<\/h4>\n<p>El sudor es un mecanismo autom\u00e1tico de protecci\u00f3n contra la temperatura exterior. Efectivamente, cuando se suda se pierde peso. Pero se recupera inmediatamente, al reponer los l\u00edquidos (imprescindibles para la salud y el rendimiento) que se han perdido con la sudoraci\u00f3n.<\/p>\n<p>Sudar abundantemente no es sin\u00f3nimo de una mayor p\u00e9rdida de peso. De hecho, la\u00a0<strong>sudoraci\u00f3n excesiva<\/strong> durante el ejercicio puede conllevar un riesgo de deshidrataci\u00f3n por la p\u00e9rdida de electrolitos a trav\u00e9s del sudor.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25030\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>2. Estirar y calentar siempre<\/h4>\n<p>En deportistas amateurs, calentar y\u00a0estirar antes de una prueba de larga distancia no es necesario. La explicaci\u00f3n est\u00e1 en que esta pr\u00e1ctica suele producir un desgaste f\u00edsico innecesario antes de iniciar un entrenamiento o una competici\u00f3n que ya es dura de por s\u00ed.<\/p>\n<p>De este modo, antes de empezar ser\u00eda aconsejable hacer un trote suave m\u00ednimo, peque\u00f1os saltos o movimientos de cintura para aumentar ligeramente la frecuencia cardiaca y entrar en calor.<\/p>\n<p>Por tanto, el calentamiento y los\u00a0estiramientos antes de una competici\u00f3n \u00fanicamente tienen sentido en los deportistas de alto nivel.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium54.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25031\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium54.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium54.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium54.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium54.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>3. El deporte aumenta el apetito<\/h4>\n<p>M\u00e1s bien al contrario: lo reduce. El ejercicio f\u00edsico aumenta la cantidad de amilina en sangre, que minimiza la sensaci\u00f3n de hambre. Adem\u00e1s correr aumenta la sensibilidad a la leptina, una hormona que liberan las c\u00e9lulas grasas avisando de que ha llegado el momento de dejar de comer.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium55.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25032\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium55.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium55.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium55.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium55.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>4. Sin dolor no hay recompensa<\/h4>\n<p>Algunos piensan que el ejercicio debe ser extenuante para ser efectivo. La mejora del rendimiento deportivo consiste en un equilibrio adecuado entre el ejercicio y el descanso. Sin embargo, esto es algo que muchas veces no contemplan ciertos deportistas, pues algunos de ellos siguen considerando que \u2018m\u00e1s es mejor\u2019.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium56.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25033\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium56.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium56.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium56.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium56.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>5. Entrenar en ayunas es mejor<\/h4>\n<p>Algunas personas tienen la creencia de que entrenar en ayunas, a primera hora de la ma\u00f1ana, ayuda a que el cuerpo utilice a la\u00a0grasa como combustible. Recordemos\u00a0que la utilizaci\u00f3n preferente de grasas como sustrato energ\u00e9tico durante el ejercicio solo se da en trabajos de muy baja intensidad. Y, tal y como se ha mencionado anteriormente, para perder peso de forma efectiva es necesario entrenar a alta intensidad.<\/p>\n<p>El problema entonces es que, cuando se hace ejercicio sin desayunar, las reservas de carbohidratos no son las id\u00f3neas para afrontar un entrenamiento intenso.<\/p>\n<p>Por ello, la recomendaci\u00f3n general, y m\u00e9dicamente m\u00e1s documentada, es la de no entrenar sin desayunar.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium57.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25034\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium57.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium57.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium57.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium57.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>6. Tomar antiinflamatorios<\/h4>\n<p>Existe la creencia de que tomar alg\u00fan antiinflamatorio (ibuprofeno o diclofenaco) o \u00e1cido acetilsalic\u00edlico antes o durante una carrera, un triatl\u00f3n o una prueba ciclista puede mitigar la aparici\u00f3n de\u00a0<strong>dolor muscular<\/strong> en el transcurso de la pr\u00e1ctica deportiva o despu\u00e9s.<\/p>\n<p>Sin embargo, los antiinflamatorios no esteroideos (AINE) no previenen el da\u00f1o muscular inducido por la actividad f\u00edsica, no evitan las molestias posteriores ni ayudan a mejorar el rendimiento f\u00edsico.<\/p>\n<p>Adem\u00e1s, cabe recordar que el consumo de antiinflamatorios tiene, entre sus efectos secundarios, la posible aparici\u00f3n de\u00a0molestias gastrointestinales.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium58.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25035\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium58.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium58.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium58.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium58.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>7. Entrenar es mejor por la ma\u00f1ana<\/h4>\n<p>Quemamos exactamente el mismo n\u00famero de calor\u00edas a las 5 de la ma\u00f1ana y a las 5 de la tarde; el rendimiento f\u00edsico suele verse reducido por la ma\u00f1ana porque la temperatura corporal est\u00e1 en su momento m\u00e1s bajo y los niveles de vitalidad tambi\u00e9n. Sin embargo, hacer ejercicios por la ma\u00f1ana despu\u00e9s de un desayuno ligero, nos da mucha energ\u00eda para el resto del d\u00eda y adem\u00e1s nos hace quemar m\u00e1s grasa, puesto que el est\u00f3mago est\u00e1 vac\u00edo y nuestro cuerpo utiliza nuestras reservas para conseguir la energ\u00eda que necesita.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium59.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25036\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium59.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium59.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium59.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium59.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>8. Toma bebidas deportivas<\/h4>\n<p>Aunque algunos afirman que las bebidas deportivas son mejores que el agua para hidratarse, \u00a0la realidad es que estas bebidas son una fuente de az\u00facar y agua. Los expertos recomiendan usar tan solo agua para la rehidrataci\u00f3n, y usar alimentos con alto contenido proteico tras un entrenamiento, ya que las prote\u00ednas ayudan al crecimiento muscular.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium60.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25037\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium60.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium60.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium60.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium60.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>9. Todos los ejercicios son saludables<\/h4>\n<p>El deporte es saludable siempre y cuando se realice correctamente. La idea de que toda pr\u00e1ctica deportiva es beneficiosa para la salud es falsa.<\/p>\n<p>El deporte puede ser contraproducente y peligroso si se realiza de forma inadecuada, sin tener en cuenta la edad, condici\u00f3n f\u00edsica y muchos otros factores.<\/p>\n<p>Se debe controlar la cantidad y la calidad, siendo conveniente buscar asesoramiento de un profesional para evitar excesos.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium61.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25038\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium61.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium61.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium61.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium61.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<h4>10. El deporte solo es para deportistas<\/h4>\n<div>\n<div>\n<p>Uno de los mitos m\u00e1s comunes es que solo los atletas profesionales pueden beneficiarse del ejercicio, cuando en realidad cualquier persona puede disfrutar de los efectos positivos de la actividad f\u00edsica, como mejorar la salud cardiovascular, reducir el estr\u00e9s y aumentar la energ\u00eda.<\/p>\n<p>No hay excusa hoy que nos impida movernos de manera saludable, divertirnos, esforzarnos por alcanzar objetivos, motivarnos para llevar una dieta correcta, relacionarnos con otras personas con un inter\u00e9s com\u00fan, y, por supuesto, educarnos en los grandes valores que el deporte, bien entendido, puede reportarnos a todos.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium62.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25039\" src=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium62.jpg?resize=730%2C410&#038;ssl=1\" alt=\"\" width=\"730\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium62.jpg?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium62.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/entrada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium62.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los mitos falsos del deporte son creencias err\u00f3neas que han persistido a lo largo del tiempo y que pueden afectar la forma en que las personas se relacionan con la actividad f\u00edsica. Son muchas las falsas creencias que rodean el mundo del deporte y la salud, algunas de ellas muy arraigadas en la poblaci\u00f3n. Estos<a class=\"moretag\" href=\"https:\/\/www.sportium.com.mx\/blog\/mitos-falsos-del-deporte\/\"><span class=\"screen-reader-text\">Leer m\u00e1s sobre Mitos Falsos del Deporte<\/span>[&#8230;]<\/a><\/p>\n","protected":false},"author":14,"featured_media":25029,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.sportium.com.mx\/blog\/wp-content\/uploads\/portada_mitos_falsos_del_deporte_club_deportivo_familiar_sportium53.jpg?fit=706%2C331&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p44S03-6uC","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/posts\/24962"}],"collection":[{"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=24962"}],"version-history":[{"count":6,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/posts\/24962\/revisions"}],"predecessor-version":[{"id":25042,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/posts\/24962\/revisions\/25042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/media\/25029"}],"wp:attachment":[{"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=24962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=24962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportium.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=24962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}